{"id":2486,"date":"2018-04-13T10:10:36","date_gmt":"2018-04-13T09:10:36","guid":{"rendered":"https:\/\/pcll.ac-dijon.fr\/eole\/?p=2486"},"modified":"2018-04-17T16:13:10","modified_gmt":"2018-04-17T15:13:10","slug":"hackathon-freeipa-samba4-ad","status":"publish","type":"post","link":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/","title":{"rendered":"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft"},"content":{"rendered":"<p>Dans le cadre du Hackathon cette seconde partie de l\u2019atelier sur FreeIPA a \u00e9t\u00e9 conduite par l\u2019\u00e9quipe du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Minist%C3%A8re_de_l%27%C3%89cologie_(France)\">minist\u00e8re de la Transition \u00e9cologique et solidaire<\/a> pour tester l\u2019utilisation de la solution <a href=\"https:\/\/www.freeipa.org\/\">FreeIPA<\/a> afin de mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft.<\/p>\n<p><a href=\"https:\/\/www.freeipa.org\/page\/About\">FreeIPA<\/a> est une solution int\u00e9gr\u00e9e de gestion d\u2019information de s\u00e9curit\u00e9 comprenant :<\/p>\n<ul>\n<li>Un serveur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Lightweight_Directory_Access_Protocol\">LDAP<\/a> <a href=\"https:\/\/fr.wikipedia.org\/wiki\/389_Directory_Server\">389 Directory Server<\/a> ;<\/li>\n<li>Un serveur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Kerberos_(protocole)\">Kerberos<\/a> <a href=\"http:\/\/web.mit.edu\/kerberos\/\">MIT Kerberos<\/a> ;<\/li>\n<li>Un serveur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Network_Time_Protocol\">NTP<\/a> <a href=\"http:\/\/www.ntp.org\">ntpd<\/a> ;<\/li>\n<li>Un serveur <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Domain_Name_System\">DNS<\/a> <a href=\"https:\/\/fr.wikipedia.org\/wiki\/BIND\">BIND<\/a> ;<\/li>\n<li>Un syst\u00e8me de gestion de certificat <a href=\"http:\/\/pki.fedoraproject.org\/wiki\/PKI_Main_Page\">Dogtag<\/a> ;<\/li>\n<li>Des interfaces d\u2019administrations : web et ligne de commandes.<\/li>\n<\/ul>\n<p>Le but est de centraliser la gestion des utilisateurs dans un v\u00e9ritable annuaire afin d\u2019outrepasser les <a href=\"https:\/\/wiki.samba.org\/index.php\/FAQ#What_Is_the_Maximum_Size_of_a_LDB_or_TDB_Database_File.3F\">limitations du nombre d\u2019objets que peut g\u00e9rer Samba4.<\/a><\/p>\n<h2>Organiser l\u2019infrastructure<\/h2>\n<div id=\"attachment_2493\" style=\"width: 295px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2493\" class=\"size-medium wp-image-2493\" src=\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-285x300.png\" alt=\"Sch\u00e9ma d\u2019un FreeIPA central avec des domaines Samba4 multiples\" width=\"285\" height=\"300\" srcset=\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-285x300.png 285w, https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-768x808.png 768w, https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-974x1024.png 974w, https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png 1280w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a><p id=\"caption-attachment-2493\" class=\"wp-caption-text\">Sch\u00e9ma d\u2019un FreeIPA central avec des domaines Samba4 multiples<\/p><\/div>\n<p>La cible est d\u2019avoir :<\/p>\n<ul>\n<li>La solution FreeIPA centralis\u00e9e qui g\u00e8re les entr\u00e9es utilisateurs ;<\/li>\n<li>Chaque site dispose de son propre domaine Active Directory g\u00e9r\u00e9 par Samba4 afin de g\u00e9rer les ressources Microsoft ;<\/li>\n<li>Les utilisateurs s\u2019authentifient sur les postes clients avec leur compte FreeIPA.<\/li>\n<\/ul>\n<h2>Ce qui fonctionne<\/h2>\n<p>Lors de cet atelier l\u2019authentification des utilisateurs du domaine FreeIPA central sur les postes clients Windows 10 int\u00e9gr\u00e9s au domaine Active Directory a \u00e9t\u00e9 valid\u00e9e.<\/p>\n<h2>Ce qui ne fonctionne pas<\/h2>\n<p>Il n\u2019est actuellement pas possible de lister les utilisateurs et groupes du domaine FreeIPA dans les outils d\u2019administration du domaine Active Directory. Il n\u2019est donc pas possible de positionner les ACLs et GPOs pour ces objets.<\/p>\n<h2>Discussion avec les d\u00e9veloppeurs FreeIPA et Samba<\/h2>\n<p>Lors de cet atelier, un contact IRC a \u00e9t\u00e9 \u00e9tabli avec les d\u00e9veloppeurs FreeIPA afin d\u2019exposer la probl\u00e9matique. Ils nous ont inform\u00e9 que cette fonctionnalit\u00e9 n\u2019\u00e9tait pas encore support\u00e9e du fait de l\u2019<a href=\"http:\/\/talks.vda.li\/2017\/SambaXP\/freeipa_gc.pdf\">absence du service de catalogue global<\/a>.<\/p>\n<p>Depuis, Daniel Dehennin a rencontr\u00e9, lors du <a href=\"https:\/\/fosdem.org\/2018\/\">FOSDEM 2018<\/a>, Alexander Bokovoy, core developer FreeIPA depuis 2011 et Samba Team member depuis 2003. Ils ont convenu d&rsquo;exposer les cas d&rsquo;usages sur un wiki public afin d&rsquo;organiser le d\u00e9veloppement des solutions possibles \u00e0 moyen et long terme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du Hackathon cette seconde partie de l\u2019atelier sur FreeIPA a \u00e9t\u00e9 conduite par l\u2019\u00e9quipe du minist\u00e8re de la Transition \u00e9cologique et solidaire pour tester l\u2019utilisation de la solution FreeIPA afin de mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft. FreeIPA est une solution int\u00e9gr\u00e9e de gestion d\u2019information de s\u00e9curit\u00e9 comprenant [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3],"tags":[77,76,74,14,72,13,73,75,84],"class_list":["post-2486","post","type-post","status-publish","format-standard","hentry","category-evenements","category-technique","tag-ad","tag-authentification","tag-centos","tag-compte-rendu","tag-freeipa","tag-hackathon","tag-kerberos","tag-ldap","tag-samba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft - EOLE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft - EOLE\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre du Hackathon cette seconde partie de l\u2019atelier sur FreeIPA a \u00e9t\u00e9 conduite par l\u2019\u00e9quipe du minist\u00e8re de la Transition \u00e9cologique et solidaire pour tester l\u2019utilisation de la solution FreeIPA afin de mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft. FreeIPA est une solution int\u00e9gr\u00e9e de gestion d\u2019information de s\u00e9curit\u00e9 comprenant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/\" \/>\n<meta property=\"og:site_name\" content=\"EOLE\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-13T09:10:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-17T15:13:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1346\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniel Dehennin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PoleEole\" \/>\n<meta name=\"twitter:site\" content=\"@PoleEole\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Dehennin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/\"},\"author\":{\"name\":\"Daniel Dehennin\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/0f74067e13a8e742cc5934103df46bcf\"},\"headline\":\"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft\",\"datePublished\":\"2018-04-13T09:10:36+00:00\",\"dateModified\":\"2018-04-17T15:13:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/\"},\"wordCount\":378,\"image\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-285x300.png\",\"keywords\":[\"AD\",\"authentification\",\"CentOS\",\"compte rendu\",\"FreeIPA\",\"Hackathon\",\"Kerberos\",\"LDAP\",\"Samba\"],\"articleSection\":[\"\u00c9v\u00e9nements\",\"Technique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/\",\"url\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/\",\"name\":\"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft - EOLE\",\"isPartOf\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-285x300.png\",\"datePublished\":\"2018-04-13T09:10:36+00:00\",\"dateModified\":\"2018-04-17T15:13:10+00:00\",\"author\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/0f74067e13a8e742cc5934103df46bcf\"},\"breadcrumb\":{\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage\",\"url\":\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png\",\"contentUrl\":\"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png\",\"width\":1280,\"height\":1346,\"caption\":\"Sch\u00e9ma d\u2019un FreeIPA central avec des domaines Samba4 multiples\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/pcll.ac-dijon.fr\/eole\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/#website\",\"url\":\"https:\/\/pcll.ac-dijon.fr\/eole\/\",\"name\":\"EOLE\",\"description\":\"Ensemble Ouvert Libre Evolutif\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pcll.ac-dijon.fr\/eole\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/0f74067e13a8e742cc5934103df46bcf\",\"name\":\"Daniel Dehennin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ca501433ed4ed83cf90454c548a4cc2cb3569000f9582e9612a0fbccaa0d585?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ca501433ed4ed83cf90454c548a4cc2cb3569000f9582e9612a0fbccaa0d585?s=96&d=mm&r=g\",\"caption\":\"Daniel Dehennin\"},\"url\":\"https:\/\/pcll.ac-dijon.fr\/eole\/author\/daniel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft - EOLE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/","og_locale":"fr_FR","og_type":"article","og_title":"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft - EOLE","og_description":"Dans le cadre du Hackathon cette seconde partie de l\u2019atelier sur FreeIPA a \u00e9t\u00e9 conduite par l\u2019\u00e9quipe du minist\u00e8re de la Transition \u00e9cologique et solidaire pour tester l\u2019utilisation de la solution FreeIPA afin de mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft. FreeIPA est une solution int\u00e9gr\u00e9e de gestion d\u2019information de s\u00e9curit\u00e9 comprenant [&hellip;]","og_url":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/","og_site_name":"EOLE","article_published_time":"2018-04-13T09:10:36+00:00","article_modified_time":"2018-04-17T15:13:10+00:00","og_image":[{"width":1280,"height":1346,"url":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png","type":"image\/png"}],"author":"Daniel Dehennin","twitter_card":"summary_large_image","twitter_creator":"@PoleEole","twitter_site":"@PoleEole","twitter_misc":{"\u00c9crit par":"Daniel Dehennin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#article","isPartOf":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/"},"author":{"name":"Daniel Dehennin","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/0f74067e13a8e742cc5934103df46bcf"},"headline":"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft","datePublished":"2018-04-13T09:10:36+00:00","dateModified":"2018-04-17T15:13:10+00:00","mainEntityOfPage":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/"},"wordCount":378,"image":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage"},"thumbnailUrl":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-285x300.png","keywords":["AD","authentification","CentOS","compte rendu","FreeIPA","Hackathon","Kerberos","LDAP","Samba"],"articleSection":["\u00c9v\u00e9nements","Technique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/","url":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/","name":"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft - EOLE","isPartOf":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage"},"image":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage"},"thumbnailUrl":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD-285x300.png","datePublished":"2018-04-13T09:10:36+00:00","dateModified":"2018-04-17T15:13:10+00:00","author":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/0f74067e13a8e742cc5934103df46bcf"},"breadcrumb":{"@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#primaryimage","url":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png","contentUrl":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-content\/uploads\/sites\/4\/2018\/01\/00-FreeIPA-Samba4-AD.png","width":1280,"height":1346,"caption":"Sch\u00e9ma d\u2019un FreeIPA central avec des domaines Samba4 multiples"},{"@type":"BreadcrumbList","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/hackathon-freeipa-samba4-ad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pcll.ac-dijon.fr\/eole\/"},{"@type":"ListItem","position":2,"name":"Hackathon : compte rendu mutualiser la gestion utilisateur dans FreeIPA pour des domaines Microsoft"}]},{"@type":"WebSite","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/#website","url":"https:\/\/pcll.ac-dijon.fr\/eole\/","name":"EOLE","description":"Ensemble Ouvert Libre Evolutif","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pcll.ac-dijon.fr\/eole\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/0f74067e13a8e742cc5934103df46bcf","name":"Daniel Dehennin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pcll.ac-dijon.fr\/eole\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ca501433ed4ed83cf90454c548a4cc2cb3569000f9582e9612a0fbccaa0d585?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ca501433ed4ed83cf90454c548a4cc2cb3569000f9582e9612a0fbccaa0d585?s=96&d=mm&r=g","caption":"Daniel Dehennin"},"url":"https:\/\/pcll.ac-dijon.fr\/eole\/author\/daniel\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/posts\/2486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/comments?post=2486"}],"version-history":[{"count":11,"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/posts\/2486\/revisions"}],"predecessor-version":[{"id":2665,"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/posts\/2486\/revisions\/2665"}],"wp:attachment":[{"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/media?parent=2486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/categories?post=2486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcll.ac-dijon.fr\/eole\/wp-json\/wp\/v2\/tags?post=2486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}